{"id":105,"date":"2015-09-25T15:16:46","date_gmt":"2015-09-25T18:16:46","guid":{"rendered":"http:\/\/www.weinberger.com.br\/blog\/?p=105"},"modified":"2020-07-15T10:10:16","modified_gmt":"2020-07-15T13:10:16","slug":"laboratorios-devem-receber-atencao-especial-e-equipes-treinadas-nos-processos-de-limpeza","status":"publish","type":"post","link":"https:\/\/www.weinberger.com.br\/blog\/laboratorios-devem-receber-atencao-especial-e-equipes-treinadas-nos-processos-de-limpeza\/","title":{"rendered":"Laborat\u00f3rios devem receber aten\u00e7\u00e3o especial e equipes treinadas nos processos de limpeza"},"content":{"rendered":"<p>Orienta\u00e7\u00f5es provenientes dos seguintes \u00f3rg\u00e3os e institui\u00e7\u00f5es como<em> NIH \u2013 National Institutes of Health (Institutos Nacionais de Sa\u00fade), CDC \u2013 Centers for Desease Control<\/em> (Centros para Controle de Doen\u00e7as), o <em>NCCLS \u2013 National Committee for Clinical Laboratory Standards (Comit\u00ea Nacional para Normas de Laborat\u00f3rios Cl\u00ednicos) e Laboratory Safety Manual \u2013 WHO \u2013 World Health Organization <\/em>definem e funcionam como um verdadeiro guia de manipula\u00e7\u00e3o em laborat\u00f3rios de an\u00e1lises cl\u00ednicas.<\/p>\n<p>Muito embora haja um esfor\u00e7o global por parte da ind\u00fastria laboratorial, qu\u00edmica e empresas com atua\u00e7\u00e3o mundial em termos de sa\u00fade, as maiores fontes de contamina\u00e7\u00e3o s\u00e3o o contato m\u00e3o-boca, o contato m\u00e3o-olho, os cortes e feridas superficiais na pele exposta e a perfura\u00e7\u00e3o cut\u00e2nea.<\/p>\n<p>Segundo dados da WHO, 41% dos 155 pa\u00edses n\u00e3o possuem padr\u00f5es ou recomenda\u00e7\u00f5es espec\u00edficas para os diferentes tipos de instala\u00e7\u00f5es de sa\u00fade ou mesmo procedimentos m\u00e9dicos especiais.<\/p>\n<p>Imagine com estes dados, o quanto as doen\u00e7as podem ser negligenciadas ou mesmo os procedimentos mais essenciais de limpeza, como \u00e9 o caso da lavagem das m\u00e3os e de cuidados ao lidar em ambientes, como os laborat\u00f3rios, por exemplo.<\/p>\n<p>Outras opera\u00e7\u00f5es, como as de homogeiniza\u00e7\u00e3o e mistura, devem levar em conta o material utilizado, dando a prefer\u00eancia para o &#8220;teflon&#8221;, j\u00e1 que o vidro ao quebrar pode liberar material infectado repentinamente. O recipiente deve ser aberto, ap\u00f3s a opera\u00e7\u00e3o, em cabine de seguran\u00e7a biol\u00f3gica.<\/p>\n<p>Cuidados especiais ainda para a abertura de ampolas contendo material seco e resfriado. Estes materiais s\u00e3o condicionados a v\u00e1cuo, podem dispersar ao serem abertos. Somente devem ser manipulados em cabines apropriadas.<\/p>\n<p>Aliados para a limpeza e manuten\u00e7\u00e3o saud\u00e1vel do ambiente laboratorial s\u00e3o as escovas industriais, que com sua ampla gama de desenhos e formatos, como as <a href=\"http:\/\/www.weinberger.com.br\/escovas-torcidas\/\">escovas torcidas<\/a> por exemplo, alcan\u00e7am uma s\u00e9rie de materiais org\u00e2nicos que poderiam se transformar em amplo risco de contamina\u00e7\u00e3o.<\/p>\n<p>\u00c9 importante que o processo de limpeza seja levado de forma assertiva e organizada, para que laborat\u00f3rios sejam tanto quanto os hospitais, vistos como uma etapa valiosa para as descobertas e o tratamento de muitas doen\u00e7as.<\/p>\n<p><strong>O que diz a ANVISA<\/strong><\/p>\n<p>De acordo com os procedimentos de limpeza, desinfec\u00e7\u00e3o e esteriliza\u00e7\u00e3o da ANVISA podemos compreender que a limpeza no ambiente laboratorial envolve o procedimento antimicrobiano de remo\u00e7\u00e3o de sujidades e detritos. Sendo a limpeza \u201co n\u00facleo de todas as a\u00e7\u00f5es referentes aos cuidados de higiene com os artigos e \u00e1reas hospitalares. \u00c9 o primeiro passo nos procedimentos t\u00e9cnicos de desinfec\u00e7\u00e3o e esteriliza\u00e7\u00e3o\u201d.<\/p>\n<p>Sobre os m\u00e9todos de limpeza, a ANVISA indica a aten\u00e7\u00e3o para os tipos de superf\u00edcies, prop\u00f3sito da \u00e1rea, sendo que a limpeza em si ir\u00e1 ser realizada via escova\u00e7\u00e3o com \u00e1gua e sab\u00e3o, fric\u00e7\u00e3o, esfrega\u00e7\u00e3o e passar pano. A varredura e espana\u00e7\u00e3o seca devem ser evitadas, pois estas pr\u00e1ticas espalham para o ar superf\u00edcies limpas, poeira, mat\u00e9ria estranha e microorganismos.<\/p>\n<p>O \u00f3rg\u00e3o ainda ressalta que programas de treinamento espec\u00edficos devem ser mantidos para garantir a efic\u00e1cia dos procedimentos de limpeza. Esses programas de treinamento devem ser aplicados ainda nos hospitais que contratam servi\u00e7os de terceiros e o monitoramento de tais processos deve ser acompanhado com aten\u00e7\u00e3o.<\/p>\n<p>Acerca da desinfec\u00e7\u00e3o &#8211; processo de destrui\u00e7\u00e3o de agentes infecciosos em forma vegetativa. Ela tamb\u00e9m deve ser realizada nas \u00e1reas e \u00e1reas e artigos semicr\u00edticos e n\u00e3o-cr\u00edticos, ou seja, s\u00e3o aquelas \u00e1reas com um certo grau de poss\u00edvel contamina\u00e7\u00e3o num hospital, mas ainda n\u00e3o consideradas cr\u00edticas.<\/p>\n<p><strong>Desinfectantes indicados para laborat\u00f3rios: <\/strong><\/p>\n<div style=\"width: 1174px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 100%;\" src=\"http:\/\/www.weinberger.com.br\/blog\/wp-content\/uploads\/2015\/08\/hipoclorito-em-v\u00e1rias-formas.png\" alt=\"hipoclorito em v\u00e1rias formas\" width=\"1164\" height=\"330\"><p class=\"wp-caption-text\">Hipoclorito em p\u00f3, solu\u00e7\u00e3o e em sua formula\u00e7\u00e3o<\/p><\/div>\n<p><strong>Hipoclorito de s\u00f3dio<\/strong><\/p>\n<p>\u00c9 um desinfetante universal ativo contra microorganismos, comumente encontrado no cloro ativo. A concentra\u00e7\u00e3o de cloro ativo deve ser no m\u00ednimo de 1g\/litro (1000 ppm). Para uma mat\u00e9ria org\u00e2nica mais densa, a concentra\u00e7\u00e3o de cloro ativo recomendada \u00e9 de 10 g\/litro (10.000 ppm).<\/p>\n<p>O hipoclorito \u00e9 corrosivo, irrita a pele, olhos e sistema respirat\u00f3rio, al\u00e9m de t\u00f3xico. Sua principal aplica\u00e7\u00e3o \u00e9 na desinfec\u00e7\u00e3o de superf\u00edcies de trabalho, materiais de vidro sujos e na descontamina\u00e7\u00e3o de superf\u00edcies de equipamentos, quando n\u00e3o houver indica\u00e7\u00e3o contr\u00e1ria.<\/p>\n<p>Muitos compostos fen\u00f3licos fazem parte das formula\u00e7\u00f5es de desinfetantes. Podem ser usados em substitui\u00e7\u00e3o ao hipoclorito de s\u00f3dio quando este n\u00e3o for poss\u00edvel.<\/p>\n<p><strong>Formalde\u00eddo<\/strong><\/p>\n<p>O formalde\u00eddo \u00e9 usado como desinfetante na concentra\u00e7\u00e3o de 50 g\/litro (5%). \u00c9 usualmente encontrado no mercado a concentra\u00e7\u00f5es de 370 g\/litro (37%). Recomenda-se contra o v\u00edrus da hepatite B.<\/p>\n<p>\u00c9 t\u00f3xico e irritante das vias a\u00e9reas, pele e olhos. \u00c9 usualmente utilizado para desinfec\u00e7\u00e3o de superf\u00edcies de trabalho, vidrarias e descontamina\u00e7\u00e3o de superf\u00edcies de equipamentos.<\/p>\n<p><strong>Iodo<\/strong><\/p>\n<p>Sua a\u00e7\u00e3o e aplica\u00e7\u00e3o s\u00e3o similares \u00e0s do hipoclorito de s\u00f3dio e \u00e9 vi\u00e1vel para o tratamento de superf\u00edcies se em concentra\u00e7\u00f5es de 0,075 g\/litro (75 ppm) e se em aus\u00eancia de prote\u00ednas. Para a lavagem das m\u00e3os, ou como esporicida, podem ser dilu\u00eddos em \u00e1lcool et\u00edlico.<\/p>\n<p>\u00c9 t\u00f3xico e irritante das vias a\u00e9reas, pele e olhos. Possui natureza corrosiva e entre outros usos, entretanto, ainda \u00e9 utilizado para desinfec\u00e7\u00e3o de superf\u00edcies de trabalho, vidrarias e descontamina\u00e7\u00e3o de superf\u00edcies de equipamentos. Para a limpeza de vidrarias s\u00e3o necess\u00e1rias escovas industriais especialmente desenvolvidas para o segmento laboratorial, como as de limpezas de frascos em diversos tamanhos, por exemplo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"471\" class=\"size-full wp-image-107\" style=\"max-width: 100%;\" src=\"http:\/\/www.weinberger.com.br\/blog\/wp-content\/uploads\/2015\/08\/Cirurgia_de_Catarata_-controle-fluidico.jpg\" alt=\"Cirurgi\u00f5es em procedimento para retirada de catarata. Instrumentos devem estar extremamente limpos para evitar a TASS\" srcset=\"https:\/\/www.weinberger.com.br\/blog\/wp-content\/uploads\/2015\/08\/Cirurgia_de_Catarata_-controle-fluidico.jpg 640w, https:\/\/www.weinberger.com.br\/blog\/wp-content\/uploads\/2015\/08\/Cirurgia_de_Catarata_-controle-fluidico-300x221.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><strong>Evitando contamina\u00e7\u00f5es e orienta\u00e7\u00f5es da <em>FDA \u2013 Food and Drug Administration (USA)<\/em><\/strong><\/p>\n<p>As causas mais comuns de<em> Toxic Anterior Segment Syndrome \u2013 TASS<\/em> &#8211;&nbsp; uso de c\u00e2nulas reutiliz\u00e1veis, limpeza inadequada dos instrumentos, uso de epinefrina preservada.<\/p>\n<p>Uso de \u00e1gua da torneira sem enx\u00e1g\u00fce final de \u00e1gua est\u00e9ril, pessoal inadequado ou bandejas para permitir uma prepara\u00e7\u00e3o adequada dos instrumentos, n\u00e3o imediata limpeza permitindo dispositivo viscoel\u00e1stico oft\u00e1lmico (ovd) e solu\u00e7\u00f5es cir\u00fargicas para secar sobre instrumentos ou reutiliza\u00e7\u00e3o de tubos.<\/p>\n<p><strong>O que diz a FDA <\/strong><\/p>\n<ol>\n<li>Este procedimento aborda os temas de recep\u00e7\u00e3o de amostra e processamento, rejei\u00e7\u00f5es de amostra, armazenamento e sua transfer\u00eancias e cust\u00f3dia para an\u00e1lise, transporte e finalmente sua elimina\u00e7\u00e3o.<\/li>\n<li>Amostras para o laborat\u00f3rio devem ser analisadas e designadas somente em salas para seu processamento.<\/li>\n<li>Para armazenamento: Este processo \u00e9 coordenador pelo supervisor do laborat\u00f3rio. As amostras s\u00e3o armazenadas congeladas, refrigeradas ou \u00e0 temperatura ambiente.<\/li>\n<\/ol>\n<p>Para a periodicidade de limpeza dos laborat\u00f3rios, a Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS) recomenda que seja feito uma limpeza que inclua o piso duas vezes ao dia. E que mensalmente uma limpeza geral incluindo teto, vidros, paredes e bancadas seja feita. Recomenda-se tamb\u00e9m uma limpeza anual de descontamina\u00e7\u00e3o atrav\u00e9s de vapores. O material mais utilizado em limpezas \u00e9 o cloro, encontrado com diferentes concentra\u00e7\u00f5es qu\u00edmicas.<\/p>\n<p><strong>Demais agentes de limpeza citados pela OMS: <\/strong><\/p>\n<ul>\n<li>Fenol quatern\u00e1rio: Possui atividade contra formas vegetativas de microorganismos, \u00e9 utilizado em pisos e \u00e9 t\u00f3xico;<\/li>\n<li>Glutaralde\u00eddo: \u00c9 eficaz contra microorganismos, \u00e9 usado em superf\u00edcies que n\u00e3o sofrem a\u00e7\u00f5es corrosivas;<\/li>\n<li>\u00c1gua Oxigenada: Desinfetante poderoso pela sua a\u00e7\u00e3o oxidativa.<\/li>\n<li>A manipula\u00e7\u00e3o de objetos de limpeza e de agentes limpantes e desinfetantes devem ser feita com o uso de equipamentos de prote\u00e7\u00e3o individual (EPI).<\/li>\n<li>Recomenda-se que cada \u00e1rea do laborat\u00f3rio tenha seus pr\u00f3prios equipamentos de limpeza (escovas, baldes, panos, recipientes) para evitar a contamina\u00e7\u00e3o.<\/li>\n<\/ul>\n<p>Todo laborat\u00f3rio deve elaborar um plano de procedimentos de emerg\u00eancia e utiliz\u00e1-lo adequadamente quando necess\u00e1rio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Orienta\u00e7\u00f5es provenientes dos seguintes \u00f3rg\u00e3os e institui\u00e7\u00f5es como NIH \u2013 National Institutes of Health (Institutos Nacionais de Sa\u00fade), CDC \u2013 Centers for Desease Control (Centros para Controle de Doen\u00e7as), o NCCLS \u2013 National Committee for Clinical Laboratory Standards (Comit\u00ea Nacional para Normas de Laborat\u00f3rios Cl\u00ednicos) e Laboratory Safety Manual \u2013 WHO \u2013 World Health Organization definem e funcionam como um verdadeiro guia de manipula\u00e7\u00e3o em laborat\u00f3rios de an\u00e1lises cl\u00ednicas. Muito<\/p>\n<p><a class=\"continue-reading\" href=\"https:\/\/www.weinberger.com.br\/blog\/laboratorios-devem-receber-atencao-especial-e-equipes-treinadas-nos-processos-de-limpeza\/\">Leia Mais&#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":138,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-setor-hospitalar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Laborat\u00f3rios devem receber aten\u00e7\u00e3o especial e equipes treinadas nos processos de limpeza - Weinberger - Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weinberger.com.br\/blog\/laboratorios-devem-receber-atencao-especial-e-equipes-treinadas-nos-processos-de-limpeza\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Laborat\u00f3rios devem receber aten\u00e7\u00e3o especial e equipes treinadas nos processos de limpeza - Weinberger - Blog\" \/>\n<meta property=\"og:description\" content=\"Orienta\u00e7\u00f5es provenientes dos seguintes \u00f3rg\u00e3os e institui\u00e7\u00f5es como NIH \u2013 National Institutes of Health (Institutos Nacionais de Sa\u00fade), CDC \u2013 Centers for Desease Control (Centros para Controle de Doen\u00e7as), o NCCLS \u2013 National Committee for Clinical Laboratory Standards (Comit\u00ea Nacional para Normas de Laborat\u00f3rios Cl\u00ednicos) e Laboratory Safety Manual \u2013 WHO \u2013 World Health Organization definem e funcionam como um verdadeiro guia de manipula\u00e7\u00e3o em laborat\u00f3rios de an\u00e1lises cl\u00ednicas. MuitoLeia Mais...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weinberger.com.br\/blog\/laboratorios-devem-receber-atencao-especial-e-equipes-treinadas-nos-processos-de-limpeza\/\" \/>\n<meta property=\"og:site_name\" content=\"Weinberger - Blog\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-25T18:16:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-15T13:10:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weinberger.com.br\/blog\/wp-content\/uploads\/2015\/09\/laboratorio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"3000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Weinberger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Weinberger\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.weinberger.com.br\/blog\/laboratorios-devem-receber-atencao-especial-e-equipes-treinadas-nos-processos-de-limpeza\/\",\"url\":\"https:\/\/www.weinberger.com.br\/blog\/laboratorios-devem-receber-atencao-especial-e-equipes-treinadas-nos-processos-de-limpeza\/\",\"name\":\"Laborat\u00f3rios devem receber aten\u00e7\u00e3o especial e equipes treinadas nos processos de limpeza - Weinberger - Blog\",\"isPartOf\":{\"@id\":\"http:\/\/www.weinberger.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.weinberger.com.br\/blog\/laboratorios-devem-receber-atencao-especial-e-equipes-treinadas-nos-processos-de-limpeza\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.weinberger.com.br\/blog\/laboratorios-devem-receber-atencao-especial-e-equipes-treinadas-nos-processos-de-limpeza\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.weinberger.com.br\/blog\/wp-content\/uploads\/2015\/09\/laboratorio.jpg\",\"datePublished\":\"2015-09-25T18:16:46+00:00\",\"dateModified\":\"2020-07-15T13:10:16+00:00\",\"author\":{\"@id\":\"http:\/\/www.weinberger.com.br\/blog\/#\/schema\/person\/c7dfc5479447632811ca1f97d27a8526\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.weinberger.com.br\/blog\/laboratorios-devem-receber-atencao-especial-e-equipes-treinadas-nos-processos-de-limpeza\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.weinberger.com.br\/blog\/laboratorios-devem-receber-atencao-especial-e-equipes-treinadas-nos-processos-de-limpeza\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.weinberger.com.br\/blog\/laboratorios-devem-receber-atencao-especial-e-equipes-treinadas-nos-processos-de-limpeza\/#primaryimage\",\"url\":\"https:\/\/www.weinberger.com.br\/blog\/wp-content\/uploads\/2015\/09\/laboratorio.jpg\",\"contentUrl\":\"https:\/\/www.weinberger.com.br\/blog\/wp-content\/uploads\/2015\/09\/laboratorio.jpg\",\"width\":3000,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.weinberger.com.br\/blog\/laboratorios-devem-receber-atencao-especial-e-equipes-treinadas-nos-processos-de-limpeza\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\/\/www.weinberger.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Laborat\u00f3rios devem receber aten\u00e7\u00e3o especial e equipes treinadas nos processos de limpeza\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.weinberger.com.br\/blog\/#website\",\"url\":\"http:\/\/www.weinberger.com.br\/blog\/\",\"name\":\"Weinberger - Blog\",\"description\":\"Escovas Industriais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/www.weinberger.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"http:\/\/www.weinberger.com.br\/blog\/#\/schema\/person\/c7dfc5479447632811ca1f97d27a8526\",\"name\":\"Weinberger\",\"url\":\"https:\/\/www.weinberger.com.br\/blog\/author\/weinberger\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Laborat\u00f3rios devem receber aten\u00e7\u00e3o especial e equipes treinadas nos processos de limpeza - Weinberger - Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weinberger.com.br\/blog\/laboratorios-devem-receber-atencao-especial-e-equipes-treinadas-nos-processos-de-limpeza\/","og_locale":"pt_BR","og_type":"article","og_title":"Laborat\u00f3rios devem receber aten\u00e7\u00e3o especial e equipes treinadas nos processos de limpeza - Weinberger - Blog","og_description":"Orienta\u00e7\u00f5es provenientes dos seguintes \u00f3rg\u00e3os e institui\u00e7\u00f5es como NIH \u2013 National Institutes of Health (Institutos Nacionais de Sa\u00fade), CDC \u2013 Centers for Desease Control (Centros para Controle de Doen\u00e7as), o NCCLS \u2013 National Committee for Clinical Laboratory Standards (Comit\u00ea Nacional para Normas de Laborat\u00f3rios Cl\u00ednicos) e Laboratory Safety Manual \u2013 WHO \u2013 World Health Organization definem e funcionam como um verdadeiro guia de manipula\u00e7\u00e3o em laborat\u00f3rios de an\u00e1lises cl\u00ednicas. MuitoLeia Mais...","og_url":"https:\/\/www.weinberger.com.br\/blog\/laboratorios-devem-receber-atencao-especial-e-equipes-treinadas-nos-processos-de-limpeza\/","og_site_name":"Weinberger - Blog","article_published_time":"2015-09-25T18:16:46+00:00","article_modified_time":"2020-07-15T13:10:16+00:00","og_image":[{"width":3000,"height":2000,"url":"https:\/\/www.weinberger.com.br\/blog\/wp-content\/uploads\/2015\/09\/laboratorio.jpg","type":"image\/jpeg"}],"author":"Weinberger","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Weinberger","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.weinberger.com.br\/blog\/laboratorios-devem-receber-atencao-especial-e-equipes-treinadas-nos-processos-de-limpeza\/","url":"https:\/\/www.weinberger.com.br\/blog\/laboratorios-devem-receber-atencao-especial-e-equipes-treinadas-nos-processos-de-limpeza\/","name":"Laborat\u00f3rios devem receber aten\u00e7\u00e3o especial e equipes treinadas nos processos de limpeza - Weinberger - Blog","isPartOf":{"@id":"http:\/\/www.weinberger.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weinberger.com.br\/blog\/laboratorios-devem-receber-atencao-especial-e-equipes-treinadas-nos-processos-de-limpeza\/#primaryimage"},"image":{"@id":"https:\/\/www.weinberger.com.br\/blog\/laboratorios-devem-receber-atencao-especial-e-equipes-treinadas-nos-processos-de-limpeza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weinberger.com.br\/blog\/wp-content\/uploads\/2015\/09\/laboratorio.jpg","datePublished":"2015-09-25T18:16:46+00:00","dateModified":"2020-07-15T13:10:16+00:00","author":{"@id":"http:\/\/www.weinberger.com.br\/blog\/#\/schema\/person\/c7dfc5479447632811ca1f97d27a8526"},"breadcrumb":{"@id":"https:\/\/www.weinberger.com.br\/blog\/laboratorios-devem-receber-atencao-especial-e-equipes-treinadas-nos-processos-de-limpeza\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weinberger.com.br\/blog\/laboratorios-devem-receber-atencao-especial-e-equipes-treinadas-nos-processos-de-limpeza\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.weinberger.com.br\/blog\/laboratorios-devem-receber-atencao-especial-e-equipes-treinadas-nos-processos-de-limpeza\/#primaryimage","url":"https:\/\/www.weinberger.com.br\/blog\/wp-content\/uploads\/2015\/09\/laboratorio.jpg","contentUrl":"https:\/\/www.weinberger.com.br\/blog\/wp-content\/uploads\/2015\/09\/laboratorio.jpg","width":3000,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/www.weinberger.com.br\/blog\/laboratorios-devem-receber-atencao-especial-e-equipes-treinadas-nos-processos-de-limpeza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/www.weinberger.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Laborat\u00f3rios devem receber aten\u00e7\u00e3o especial e equipes treinadas nos processos de limpeza"}]},{"@type":"WebSite","@id":"http:\/\/www.weinberger.com.br\/blog\/#website","url":"http:\/\/www.weinberger.com.br\/blog\/","name":"Weinberger - Blog","description":"Escovas Industriais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.weinberger.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"http:\/\/www.weinberger.com.br\/blog\/#\/schema\/person\/c7dfc5479447632811ca1f97d27a8526","name":"Weinberger","url":"https:\/\/www.weinberger.com.br\/blog\/author\/weinberger\/"}]}},"_links":{"self":[{"href":"https:\/\/www.weinberger.com.br\/blog\/wp-json\/wp\/v2\/posts\/105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weinberger.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weinberger.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weinberger.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weinberger.com.br\/blog\/wp-json\/wp\/v2\/comments?post=105"}],"version-history":[{"count":6,"href":"https:\/\/www.weinberger.com.br\/blog\/wp-json\/wp\/v2\/posts\/105\/revisions"}],"predecessor-version":[{"id":832,"href":"https:\/\/www.weinberger.com.br\/blog\/wp-json\/wp\/v2\/posts\/105\/revisions\/832"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weinberger.com.br\/blog\/wp-json\/wp\/v2\/media\/138"}],"wp:attachment":[{"href":"https:\/\/www.weinberger.com.br\/blog\/wp-json\/wp\/v2\/media?parent=105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weinberger.com.br\/blog\/wp-json\/wp\/v2\/categories?post=105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weinberger.com.br\/blog\/wp-json\/wp\/v2\/tags?post=105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}